{"id":24690,"date":"2025-02-28T19:44:00","date_gmt":"2025-03-01T00:44:00","guid":{"rendered":"https:\/\/workersvoiceus.org\/?p=24690"},"modified":"2025-03-01T18:55:16","modified_gmt":"2025-03-01T23:55:16","slug":"trump-engineers-a-stunning-shift-in-u-s-foreign-policy","status":"publish","type":"post","link":"https:\/\/workersvoiceus.org\/es\/2025\/02\/28\/trump-engineers-a-stunning-shift-in-u-s-foreign-policy\/","title":{"rendered":"Trump da un giro impresionante en la pol\u00edtica exterior"},"content":{"rendered":"<p style=\"text-align: center;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"24693\" data-permalink=\"https:\/\/workersvoiceus.org\/es\/2025\/02\/28\/trump-engineers-a-stunning-shift-in-u-s-foreign-policy\/usa-zelensky-trump\/\" data-orig-file=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2025\/02\/USA-ZELENSKY-TRUMP.jpg?fit=650%2C434&amp;ssl=1\" data-orig-size=\"650,434\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"USA-ZELENSKY-TRUMP\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2025\/02\/USA-ZELENSKY-TRUMP.jpg?fit=650%2C434&amp;ssl=1\" class=\"alignnone size-full wp-image-24693\" src=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2025\/02\/USA-ZELENSKY-TRUMP.jpg?resize=650%2C434&#038;ssl=1\" alt=\"\" width=\"650\" height=\"434\" srcset=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2025\/02\/USA-ZELENSKY-TRUMP.jpg?w=650&amp;ssl=1 650w, https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2025\/02\/USA-ZELENSKY-TRUMP.jpg?resize=300%2C200&amp;ssl=1 300w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/p>\n<p style=\"text-align: center;\"><b>Por ERNIE GOTTA<\/b><\/p>\n<p>La administraci\u00f3n Trump ha sorprendido al mundo con un giro radical en pol\u00edtica exterior. Una de las expresiones m\u00e1s crudas de la nueva pol\u00edtica tuvo lugar el 28 de febrero cuando, en una explosiva pelea a gritos en la Casa Blanca, el presidente Trump y el vicepresidente Vance se unieron para humillar al dirigente ucraniano Vladimir Zelensky por ser \u00abirrespetuoso\u00bb con EEUU. La sesi\u00f3n se hab\u00eda convocado en el contexto de un inminente \u00abacuerdo\u00bb (robo) en el que EEUU obtendr\u00eda el derecho a extraer recursos minerales clave de Ucrania. Sin embargo, al final de la reuni\u00f3n, Trump declar\u00f3 bruscamente a Zelensky: \u00ab\u00a1O haces un trato o nos vamos!\u00bb. A continuaci\u00f3n, pidi\u00f3 a Zelensky que abandonara la Casa Blanca.<\/p>\n<p>La reuni\u00f3n se produjo tras otras declaraciones chocantes de funcionarios estadounidenses en las primeras semanas de la administraci\u00f3n Trump. En su conjunto, fueron interpretadas por muchos comentaristas como una expresi\u00f3n de la destrucci\u00f3n del orden mundial posterior a la Segunda Guerra Mundial en favor de una nueva configuraci\u00f3n que se consideraba m\u00e1s beneficiosa para el imperialismo estadounidense.<\/p>\n<p><b>Elementos del cambio de pol\u00edtica estadounidense<\/b><\/p>\n<p>El 24 de febrero, Estados Unidos se neg\u00f3 a votar a favor de una resoluci\u00f3n de la ONU que condenaba a Rusia en el tercer aniversario de la invasi\u00f3n de Ucrania por ese pa\u00eds. La votaci\u00f3n se produjo tras tres discursos impresionantes de la administraci\u00f3n Trump:<\/p>\n<p>El secretario de Defensa, Pete Hegseth, en una reuni\u00f3n celebrada el 12 de febrero en Bruselas con el Grupo de Contacto de Defensa de Ucrania, dej\u00f3 claro que Estados Unidos daba prioridad a contener a China, y no a Rusia. Dijo: \u00abS\u00f3lo pondremos fin a esta guerra devastadora -y estableceremos una paz duradera- combinando la fuerza aliada con una evaluaci\u00f3n realista del campo de batalla. Queremos, como ustedes, una Ucrania soberana y pr\u00f3spera. Pero debemos empezar por reconocer que volver a las fronteras de Ucrania anteriores a 2014 es un objetivo poco realista.\u00bb Implor\u00f3 a los miembros europeos del Grupo de Contacto de Defensa de Ucrania que donen m\u00e1s munici\u00f3n y gasten m\u00e1s en defensa.<\/p>\n<p>Hegseth expuso las prioridades de Estados Unidos: \u00abEstados Unidos se enfrenta a amenazas importantes para nuestra patria. Debemos centrarnos -y lo estamos haciendo- en la seguridad de nuestras propias fronteras. Tambi\u00e9n nos enfrentamos a un competidor semejante, los chinos comunistas, con la capacidad y la intenci\u00f3n de amenazar nuestra patria y nuestros principales intereses nacionales en el Indo-Pac\u00edfico. Estados Unidos est\u00e1 dando prioridad a la disuasi\u00f3n de la guerra con China en el Pac\u00edfico&#8230;\u00bb.<\/p>\n<p>Dos d\u00edas despu\u00e9s, en la Conferencia de Seguridad de M\u00fanich, JD Vance profundiz\u00f3 en la actitud de la administraci\u00f3n Trump hacia gran parte de Europa. Frente a pol\u00edticos capitalistas y oficiales militares europeos, se burl\u00f3 de las \u00abdemocracias\u00bb liberales europeas diciendo que la mayor amenaza no era externa, sino interna. Vance compar\u00f3 los \u00abcortafuegos\u00bb europeos contra la colaboraci\u00f3n electoral con partidos de origen fascista con la censura de la libertad de expresi\u00f3n. Compar\u00f3 la detenci\u00f3n en el Reino Unido de un manifestante antiaborto que hab\u00eda violado la zona de seguridad de una cl\u00ednica con la represi\u00f3n estalinista de los disidentes, y describi\u00f3 una imagen de represi\u00f3n liberal contra los cristianos y las personas que tienen creencias pol\u00edticas de extrema derecha y pertenecen a organizaciones pol\u00edticas de extrema derecha.<\/p>\n<p>Vance se acerc\u00f3 a la derecha europea celebrando los \u00abvalores compartidos y la civilizaci\u00f3n de Europa y Estados Unidos\u00bb, un silbido para los defensores de la supremac\u00eda blanca, el anticomunismo y el tradicionalismo reaccionario. Tambi\u00e9n hizo todo lo posible por reunirse con Alice Weidel, l\u00edder del AfD alem\u00e1n de extrema derecha, que obtuvo importantes avances en las elecciones alemanas. Vance y Weidel hablaron sobre la guerra de Ucrania, la pol\u00edtica interior alemana y la libertad de expresi\u00f3n.<\/p>\n<p>La nueva realidad de la reconfiguraci\u00f3n de las alianzas fue abrumadora para algunos pol\u00edticos europeos. En la clausura de la Conferencia de Seguridad de M\u00fanich, el presidente, Christopher Heusgen, un diplom\u00e1tico alem\u00e1n, se emocion\u00f3 al afirmar: \u00abEst\u00e1 claro que nuestro orden internacional basado en normas est\u00e1 bajo presi\u00f3n. [&#8230;] Creo firmemente [&#8230;] que este mundo multipolar debe basarse en un conjunto \u00fanico de normas y principios, en la Carta de las Naciones Unidas y en la Declaraci\u00f3n Universal de los Derechos Humanos. Este orden es f\u00e1cil de perturbar, es f\u00e1cil de destruir, pero es mucho m\u00e1s dif\u00edcil de reconstruir, as\u00ed que aferr\u00e9monos a estos valores. No los reinventemos, sino que centremos nuestros esfuerzos en fortalecer su aplicaci\u00f3n coherente\u00bb.<\/p>\n<p>D\u00edas despu\u00e9s, el 18 de febrero, el secretario de Estado, Marco Rubio, se reuni\u00f3 en Riad, Arabia Saud\u00ed, con su hom\u00f3logo ruso, Sergey Lavrov, para discutir el restablecimiento de las relaciones diplom\u00e1ticas con el fin de llegar a un acuerdo de paz en la guerra con Ucrania. Ucrania qued\u00f3 fuera de la reuni\u00f3n, y el presidente Trump lleg\u00f3 a decir que el presidente ucraniano Zelensky era un \u00abdictador sin elecciones\u00bb.<\/p>\n<p>Lavrov le dijo a Rubio que Rusia abrir\u00eda oportunidades para la inversi\u00f3n estadounidense y el acceso a minerales. Acordaron establecer formas de consultarse para abordar las quejas y reabrir las misiones diplom\u00e1ticas. Bas\u00e1ndose en un supuesto acuerdo para permitir que Rusia contin\u00fae ocupando el rico territorio ucraniano, hablaron de una futura cooperaci\u00f3n en cuestiones de inter\u00e9s nacional y de oportunidades de inversi\u00f3n \u00abhist\u00f3ricas\u00bb.<\/p>\n<p><b>Los pa\u00edses capitalistas en crisis<\/b><\/p>\n<p>Este es un cambio dram\u00e1tico con respecto al a\u00f1o anterior, cuando Estados Unidos, bajo la administraci\u00f3n Biden, dio a Ucrania suficiente apoyo militar para mantener viva su defensa. Esto estaba en consonancia con una alianza estrat\u00e9gica con una Europa temerosa de la invasi\u00f3n rusa en otras zonas fronterizas. Ahora, Washington ve su futuro mejor servido si juega con Rusia.<\/p>\n<p>La expectativa de EE. UU. en estos cambios es que Europa comience a ampliar los presupuestos de guerra y los gastos de defensa. \u00bfC\u00f3mo pagar\u00e1n los pa\u00edses de la UE que han dependido de la ayuda estadounidense durante d\u00e9cadas para defender Europa? Una forma es flexibilizar las leyes que limitan el gasto. Otra forma ser\u00eda recortar los programas sociales para financiar los gastos de defensa. Programas en Europa como la asistencia sanitaria universal y los subsidios familiares que han sido la envidia de los trabajadores en EE. UU. estar\u00e1n en la picota.<\/p>\n<p>Las naciones de la UE tambi\u00e9n recortar\u00e1n dr\u00e1sticamente la ayuda al mundo en desarrollo, reflejando la disoluci\u00f3n de USAID por parte de EE. UU. El temor entre los capitalistas europeos es que recortar el bienestar social a favor de las armas desate protestas y huelgas de trabajadores y j\u00f3venes en todo el continente como las que vimos en Gran Breta\u00f1a y Francia en 2023.<\/p>\n<p>Otro aspecto de este giro pol\u00edtico es que la clase capitalista estadounidense reconoce el auge de Rusia y China como nuevas potencias imperialistas. Esto significa que los recursos y los mercados de todo el mundo deben ser redistribuidos. \u00bfQui\u00e9n tendr\u00e1 la ventaja? Claramente, China sigue siendo el principal competidor econ\u00f3mico y militar de EE. UU. La pregunta es c\u00f3mo el imperialismo estadounidense puede contener a China y mantener la rentabilidad.<\/p>\n<p>Este cambio hist\u00f3rico est\u00e1 vinculado a una nueva estrategia estadounidense para competir con China en un per\u00edodo de declive econ\u00f3mico. Este declive empuj\u00f3 a Biden a retirar tropas de Afganist\u00e1n para reforzar la presencia militar en el Pac\u00edfico.<\/p>\n<p>Hoy en d\u00eda, una parte de los capitalistas estadounidenses est\u00e1 adoptando un enfoque diferente, que se parece al libro de jugadas del Proyecto 2025 elaborado por la Heritage Foundation. En cuanto a la pol\u00edtica exterior de EE. UU., el Proyecto 2025 trata de analizar los costes frente a los beneficios para Estados Unidos. La intenci\u00f3n es eliminar el \u00abgasto innecesario\u00bb, que debilitar\u00eda organizaciones internacionales y nacionales como la OTAN, la Organizaci\u00f3n Mundial de la Salud y USAID. Por supuesto, la OTAN y USAID eran extensiones del imperialismo estadounidense que utilizaban el poder duro y blando para proyectar y proteger los intereses de EE. UU.<\/p>\n<p>\u00bfPor qu\u00e9 Trump considera que se trata de un gasto innecesario? Sabemos que Estados Unidos est\u00e1 muy lejos de poder producir suficiente equipamiento militar para la guerra. Parte del ascenso de Trump al poder est\u00e1 directamente relacionado con su capacidad para poner a Estados Unidos en pie de guerra para contener a China. La necesidad de un nuevo refuerzo militar y de cambios importantes en el Departamento de Defensa tambi\u00e9n se esbozan en el Proyecto 2025. Esto incluye estrategias en torno a la guerra irregular, los tipos de adquisici\u00f3n de armas necesarios, con qui\u00e9n deber\u00edan aliarse los EE. UU. y mucho m\u00e1s.<\/p>\n<p>En mayo de 2024, Roger Wicker, senador de Misisipi, dijo: \u00abYa es hora de reconstruir el ej\u00e9rcito estadounidense. Podemos evitar la guerra prepar\u00e1ndonos para ella. Cuando los altos mandos militares de Estados Unidos testifican ante mis colegas y yo en el Comit\u00e9 de Servicios Armados del Senado de EE. UU. Senate Armed Services Committee a puerta cerrada, han dicho que nos enfrentamos a algunos de los entornos de amenaza global m\u00e1s peligrosos desde la Segunda Guerra Mundial. Luego, oscurecen ese panorama ya inquietante al explicar que nuestras fuerzas armadas corren el riesgo de estar mal equipadas y desarmadas. Luchamos por construir y mantener barcos, nuestra flota de aviones de combate es peligrosamente peque\u00f1a y nuestra infraestructura militar est\u00e1 obsoleta. Mientras tanto, los adversarios de Estados Unidos est\u00e1n aumentando sus ej\u00e9rcitos y volvi\u00e9ndose m\u00e1s agresivos\u00bb.<\/p>\n<p>Las personas que se beneficiar\u00e1n de estos cambios son multimillonarios tecnol\u00f3gicos de extrema derecha como Peter Thiel y Elon Musk, que obtendr\u00e1n miles de millones en contratos gubernamentales. Estos multimillonarios se consideran a s\u00ed mismos la \u00abcontra\u00e9lite\u00bb y quieren destruir lo que ven como el orden \u00abglobalista\u00bb. Musk est\u00e1 interviniendo abiertamente en el gobierno. Por un lado, est\u00e1 recortando programas y departamentos, y por otro, est\u00e1 aceptando miles de millones de d\u00f3lares en subsidios gubernamentales para SpaceX. <i>Fortune.com <\/i>escribe: \u00abLa directora ejecutiva de SpaceX, Gwynne Shotwell, ha dicho que la empresa tiene 22 000 millones de d\u00f3lares en contratos gubernamentales, inform\u00f3 Reuters. La empresa de veh\u00edculos el\u00e9ctricos Tesla, cuyas acciones constituyen la mayor parte del patrimonio neto de casi 400 000 millones de d\u00f3lares de Musk, se ha beneficiado de 2800 millones de d\u00f3lares en subvenciones o ayudas fiscales, seg\u00fan el rastreador de subvenciones Good Jobs First\u00bb.<\/p>\n<p><b>\u00bfQu\u00e9 significa esto para la clase trabajadora?<\/b><\/p>\n<p>Las declaraciones de Trump de \u00abAm\u00e9rica primero\u00bb se\u00f1alan un esfuerzo concentrado de Estados Unidos por reafirmarse como superpotencia preeminente en el mundo, por encima de rivales como China. Mientras se toman medidas para aumentar la financiaci\u00f3n de una fuerza militar estadounidense modernizada y de alta tecnolog\u00eda, el presidente ha dejado claro que Washington pretende amenazar e intimidar a otros gobiernos para salirse con la suya. La administraci\u00f3n ha demostrado que est\u00e1 dispuesta a hacerse pasar por \u00abpacificadora\u00bb cuando esa t\u00e1ctica le parezca \u00fatil, pero que desatar\u00e1 su poder militar si es necesario.<\/p>\n<p>Los trabajadores no tienen nada que ver ni con los conflictos internacionales econ\u00f3micos actuales ni con la inminente guerra de destrucci\u00f3n militar. Si Estados Unidos entrara de lleno en la guerra, podr\u00edamos esperar tambi\u00e9n a dr\u00e1sticos cambios internos: la reinstauraci\u00f3n del servicio militar obligatorio, la represi\u00f3n de la disidencia, los esfuerzos por regimentar el trabajo y prohibir las huelgas, y el continuo desmantelamiento de los programas sociales y las normativas que afectan a la producci\u00f3n empresarial.<\/p>\n<p>Algunos sectores de la Am\u00e9rica corporativa creen que las pol\u00edticas de Trump ayudar\u00e1n a sus resultados en la escena mundial. Pero, en \u00faltima instancia, los capitalistas tienen pocos medios para aumentar sus beneficios que no sean aumentar su explotaci\u00f3n de la clase trabajadora. Para contraatacar, los trabajadores y sus aliados s\u00f3lo pueden depender de s\u00ed mismos. Los pol\u00edticos del Partido Dem\u00f3crata pretenden ofrecer liderazgo, pero no tienen respuestas verdaderas. Necesitamos organizarnos en nuestros lugares de trabajo y sindicatos, escuelas y comunidades para movilizar a millones de personas en las calles en una respuesta poderosa y unida a la agenda de Trump.<\/p>\n<p>\u00a1Dinero para la vivienda, la sanidad y la mitigaci\u00f3n del cambio clim\u00e1tico, no para el Pent\u00e1gono! \u00a1Autodeterminaci\u00f3n para Palestina y Ucrania!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por ERNIE GOTTA La administraci\u00f3n Trump ha sorprendido al mundo con un giro radical en pol\u00edtica exterior. Una de las expresiones m\u00e1s crudas de la nueva pol\u00edtica tuvo lugar el 28 de febrero cuando, en una explosiva pelea a gritos en la Casa Blanca, el presidente Trump y el vicepresidente Vance se unieron para humillar [&hellip;]<\/p>\n","protected":false},"author":13882115,"featured_media":24693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[27645,27646,27799],"tags":[31336,31335,31119,30188,27933,31219,27642,31315,30729],"class_list":["post-24690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antiwar","category-europe","category-national","tag-hegseth","tag-munich","tag-musk","tag-putin","tag-russia","tag-trump-2","tag-ukraine","tag-vance","tag-zelensky"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2025\/02\/USA-ZELENSKY-TRUMP.jpg?fit=650%2C434&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdQxqk-6qe","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts\/24690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/users\/13882115"}],"replies":[{"embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/comments?post=24690"}],"version-history":[{"count":6,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts\/24690\/revisions"}],"predecessor-version":[{"id":24704,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts\/24690\/revisions\/24704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/media\/24693"}],"wp:attachment":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/media?parent=24690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/categories?post=24690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/tags?post=24690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}