{"id":17817,"date":"2023-07-22T20:54:01","date_gmt":"2023-07-23T00:54:01","guid":{"rendered":"https:\/\/workersvoiceus.org\/?p=17817"},"modified":"2023-07-22T23:36:03","modified_gmt":"2023-07-23T03:36:03","slug":"hollywood-on-strike","status":"publish","type":"post","link":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/","title":{"rendered":"Hollywood en huelga"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"17819\" data-permalink=\"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/writers-robert-hanashiro-usa-today\/\" data-orig-file=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?fit=660%2C415&amp;ssl=1\" data-orig-size=\"660,415\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Writers Robert Hanashiro : USA Today\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?fit=660%2C415&amp;ssl=1\" class=\"wp-image-17819 aligncenter\" src=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?resize=678%2C427&#038;ssl=1\" alt=\"\" width=\"678\" height=\"427\" srcset=\"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?resize=300%2C189&amp;ssl=1 300w, https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?w=660&amp;ssl=1 660w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Por HERMAN MORRIS<\/strong><\/p>\n<p>El 2 de mayo, m\u00e1s de 11.000 trabajadores del Sindicato de Guionistas de Estados Unidos (WGA) abandonaron el trabajo e iniciaron su segunda huelga del siglo XXI. Lo que est\u00e1 en juego para los trabajadores de la industria son los salarios residuales, los requisitos m\u00ednimos de personal y la automatizaci\u00f3n del trabajo por la IA.<\/p>\n<p>Escritores de todo el pa\u00eds est\u00e1n haciendo piquetes en estudios y lugares de rodaje de la zona de Los \u00c1ngeles y Nueva York. Desde el 14 de julio, m\u00e1s de 160.000 actores representados por SAG-AFTRA tambi\u00e9n se han unido a los piquetes en protesta por el trato injusto que les ofrece la Alianza de Productores de Cine y Televisi\u00f3n (AMPTP). Es la primera vez desde 1960 que tanto actores como escritores se declaran en huelga; su acci\u00f3n ha paralizado de hecho todo el sistema de producci\u00f3n de cine y televisi\u00f3n que dirige Hollywood.<\/p>\n<p><strong>Lo que est\u00e1 en juego<\/strong><\/p>\n<p>El principal cambio en la industria de la escritura y la interpretaci\u00f3n desde las huelgas anteriores es que el streaming ha trastocado por completo el modelo de distribuci\u00f3n y pagos al que estaban acostumbrados los trabajadores. En el pasado, los escritores y actores recib\u00edan cheques residuales cada vez que una obra producida por ellos se emit\u00eda de nuevo en una cadena de televisi\u00f3n o se republicaba en disco o casete. Ahora, en la era del streaming, no existen tales protecciones para las producciones que s\u00f3lo se emiten en streaming. Las empresas de streaming pagan a los escritores un \u00fanico cheque residual inicial por la subida nacional y extranjera de una obra a su servicio, que se basa en el n\u00famero total de abonados de la plataforma. No se hace ninguna diferenciaci\u00f3n para los programas que son m\u00e1s grandes que otros.<\/p>\n<p>Adem\u00e1s, las series que llegan a los servicios de streaming suelen tener un n\u00famero de episodios m\u00e1s corto, con temporadas de 8-10 episodios frente a los 20-30 de las cadenas de televisi\u00f3n. Cada episodio tiene derecho a su propio pago residual. Al reducir el n\u00famero de episodios y no recompensar a las series de \u00e9xito que atraen suscriptores a las plataformas de streaming, los servicios de streaming pueden sacar el m\u00e1ximo partido a los escritores y actores mientras les dan una fracci\u00f3n de lo que les habr\u00edan debido si su serie se hubiera emitido en una cadena de televisi\u00f3n o en una pel\u00edcula.<\/p>\n<p>Esto significa que los escritores que trabajan en series de gran prestigio que se emiten en streaming, como &#8220;Stranger Things&#8221;, &#8220;The Mandalorian&#8221; o &#8220;The Handmaid&#8217;s Tale&#8221;, a menudo ganan lo mismo o menos que un escritor que trabaja en un procedimiento policial de televisi\u00f3n de peque\u00f1o presupuesto, que puede proporcionar varios meses de paga a escritores y actores en el plat\u00f3 o en la sala y varios cheques residuales m\u00e1s cuando las series m\u00e1s largas se emiten en la cadena de televisi\u00f3n. Cuando el equipo negociador del WGA present\u00f3 la propuesta de pagar los residuales en funci\u00f3n de la audiencia por programa, fue rechazada sin contraoferta.<\/p>\n<p>Adem\u00e1s, los escritores se enfrentan a recortes de personal. Muchas cadenas de televisi\u00f3n contratan a un equipo inicial completo de escritores para sus programas y luego reducen al m\u00ednimo el personal contratado una vez finalizada la preproducci\u00f3n de una temporada, dejando s\u00f3lo a un pu\u00f1ado del personal inicial para completar el trabajo. Los escritores han exigido un m\u00ednimo de personal y una garant\u00eda m\u00ednima de 10 semanas de trabajo para la contrataci\u00f3n de un espect\u00e1culo; pero ambas demandas han sido rechazadas, sin contraoferta alguna.<\/p>\n<p>Por \u00faltimo, al gremio de los escritores le preocupa la IA generativa. Los empleadores tienen un gran inter\u00e9s en la IA, como los LLM y el software de generaci\u00f3n de im\u00e1genes, para empezar a aumentar el ritmo de trabajo y automatizar los puestos de trabajo. Los miembros de la SAG-AFTRA tambi\u00e9n est\u00e1n preocupados por el uso que la IA pueda hacer de la imagen de los actores, una cuesti\u00f3n sobre la que la AMPTP ni siquiera se ha puesto de acuerdo. El WGA exigi\u00f3 que no se utilizara IA para escribir o reescribir material y que se impidiera que los guionistas a los que representa utilizaran las fuentes de AI para generar trabajo. Esta exigencia fue rechazada, sin contraoferta.<\/p>\n<p>En total, el WGA pide obtener 429 millones de d\u00f3lares m\u00e1s al a\u00f1o en salarios y beneficios para sus miembros. Hollywood ofrece de vuelta 86 millones de d\u00f3lares. Solo en los a\u00f1os 2018-2022, David Zaslav (CEO de Warner Bros Discovery) gan\u00f3 498 millones de d\u00f3lares . El hecho es que, incluso con los actuales problemas financieros que enfrenta Hollywood con las p\u00e9rdidas de streaming y la disminuci\u00f3n de las ventas de entradas despu\u00e9s de la pandemia, los estudios ganan m\u00e1s que suficiente dinero para dar a la WGA cada centavo que est\u00e1n pidiendo y m\u00e1s, pero quieren exprimir a los trabajadores por cada centavo que tienen.<\/p>\n<p><strong>Los productores destripan la industria, los trabajadores soportan el coste<\/strong><\/p>\n<p>Desde la \u00faltima huelga de guionistas de 2007, el streaming ha pasado a dominar la industria del cine y la televisi\u00f3n. Casi todas las cadenas de televisi\u00f3n y estudios de cine forman parte o poseen su propio servicio de streaming. Como parte de estas inversiones en streaming, el n\u00famero de programas producidos se ha disparado, pasando de un total de 210 en 2009 a 599 en 2023. Adem\u00e1s de dispararse los presupuestos de producci\u00f3n, los estudios han recurrido a medidas de recorte de costes, como la reducci\u00f3n del n\u00famero de guionistas contratados para una temporada de televisi\u00f3n, la sustituci\u00f3n de los caros decorados y atrezo (fabricados por los sindicatos) por CGI y efectos digitales producidos por artistas en su mayor\u00eda no sindicados, y el truco financiero de poner una serie o pel\u00edcula en una plataforma de streaming en lugar de en otros modelos de estreno para evitar mayores pagos residuales.<\/p>\n<p>A pesar de todas estas medidas, sigue sin demostrarse que los servicios de streaming sean un modelo sustancialmente rentable para los estudios. Disney ha perdido hasta ahora m\u00e1s de 10.000 millones de d\u00f3lares en streaming y no prev\u00e9 ser rentable hasta 2024. La plataforma Max de Warner Bros Discovery (antes HBO Max) tampoco es rentable, y s\u00f3lo ahora aspira a serlo a finales de 2023, al culminar una serie de fusiones que, en parte, pretend\u00edan aumentar el n\u00famero de programas en el servicio.<\/p>\n<p>Ahora que la maquinaria de Hollywood y la burocracia de Wall Street que la gobierna se enfrentan a la realidad de que han tomado malas decisiones de inversi\u00f3n dentro de la industria, vuelven a la \u00fanica forma de aumentar los beneficios que les queda. Este ha sido y ser\u00e1 siempre el intento de empobrecer a la clase trabajadora que es la savia de la industria que esta gente gobierna. La presidenta de SAG-AFTRA, Fran Drescher, ten\u00eda raz\u00f3n al se\u00f1alar que esta lucha es mucho m\u00e1s grande que la de los actores y escritores, al afirmar: &#8220;Lo que ocurre aqu\u00ed es importante porque lo que nos est\u00e1 pasando a nosotros ocurre en todos los \u00e1mbitos laborales, cuando los empresarios hacen de Wall Street y la avaricia su prioridad y se olvidan de los colaboradores esenciales que hacen funcionar la m\u00e1quina.&#8221; Los intentos de automatizaci\u00f3n y disciplinamiento laboral se avecinan para la clase trabajadora en todas partes mientras se cierne la posibilidad de una gran recesi\u00f3n. Incluso teniendo en cuenta todos estos males financieros, s\u00f3lo la huelga de la WGA sigue pidiendo aproximadamente la mitad de lo que ganaron el a\u00f1o pasado ocho directores ejecutivos de Hollywood, un total de 773 millones de d\u00f3lares.<\/p>\n<p>La \u00fanica herramienta real que tiene la clase trabajadora en estas situaciones es recurrir a sus organizaciones militantes de autodefensa y a la huelga. Pero m\u00e1s all\u00e1 de eso, es necesario que esta lucha salga de los confines de la lucha sindical. Mientras los trabajadores est\u00e9n atrapados en un sistema capitalista en el que la tasa de beneficios tiende a caer a medida que las industrias maduran, estar\u00e1n librando una batalla en t\u00e9rminos capitalistas y en tribunales burgueses. S\u00f3lo una revoluci\u00f3n y la abolici\u00f3n del sistema capitalista de trabajo asalariado, sustituy\u00e9ndolo por uno organizado por y para la clase obrera, puede poner fin a los constantes ataques a los medios de subsistencia de los trabajadores.<\/p>\n<p>La Voz de los Trabajadores apoya a SAG-AFTRA y WGA en su lucha contra la codicia de Hollywood y Wall Street. Animamos a todos los que vivan cerca de una l\u00ednea de piquete en Nueva York, Los \u00c1ngeles u otras ciudades a que salgan y muestren su apoyo a los que protestan por un salario y un contrato justos. \u00a1Solidaridad con los actores y guionistas!<\/p>\n<p><em>Foto: Los guionistas forman un piquete en los estudios Disney el 2 de mayo. (Robert Hanahiro \/ USA Today)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Por HERMAN MORRIS El 2 de mayo, m\u00e1s de 11.000 trabajadores del Sindicato de Guionistas de Estados Unidos (WGA) abandonaron el trabajo e iniciaron su segunda huelga del siglo XXI. Lo que est\u00e1 en juego para los trabajadores de la industria son los salarios residuales, los requisitos m\u00ednimos de personal y la automatizaci\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":13882115,"featured_media":17819,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[30705,30713],"tags":[],"class_list":["post-17817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-the-arts","category-labor"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"philahistory\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Voz de los Trabajadores - Una fusion de Socialist Resurgence y La Voz de los Trabajadores\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Hollywood en huelga - Workers&#039; Voice\/La Voz\" \/>\n\t\t<meta property=\"og:description\" content=\"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-07-23T00:54:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-07-23T03:36:03+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/workersvoiceus\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@WorkersVoice_US\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Hollywood en huelga - Workers&#039; Voice\/La Voz\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@WorkersVoice_US\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#blogposting\",\"name\":\"Hollywood en huelga - Workers' Voice\\\/La Voz\",\"headline\":\"Hollywood en huelga\",\"author\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/author\\\/philahistory\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/workersvoiceus.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Writers-Robert-Hanashiro-USA-Today.webp?fit=660%2C415&ssl=1\",\"width\":660,\"height\":415},\"datePublished\":\"2023-07-22T20:54:01-04:00\",\"dateModified\":\"2023-07-22T23:36:03-04:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#webpage\"},\"articleSection\":\"Books, films, arts | Libros, peliculas, arte, Labor | Lucha obrera\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/workersvoiceus.org\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/category\\\/the-arts\\\/#listItem\",\"name\":\"Books, films, arts | Libros, peliculas, arte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/category\\\/the-arts\\\/#listItem\",\"position\":2,\"name\":\"Books, films, arts | Libros, peliculas, arte\",\"item\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/category\\\/the-arts\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#listItem\",\"name\":\"Hollywood en huelga\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#listItem\",\"position\":3,\"name\":\"Hollywood en huelga\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/category\\\/the-arts\\\/#listItem\",\"name\":\"Books, films, arts | Libros, peliculas, arte\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/#organization\",\"name\":\"Workers' Voice\\\/La Voz de los Trabajadores\",\"description\":\"Una fusion de Socialist Resurgence y La Voz de los Trabajadores\",\"url\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/workersvoiceus\",\"https:\\\/\\\/twitter.com\\\/WorkersVoice_US\",\"https:\\\/\\\/www.instagram.com\\\/workersvoiceus\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/author\\\/philahistory\\\/#author\",\"url\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/author\\\/philahistory\\\/\",\"name\":\"philahistory\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4060a01da4b5637608d72866d0d000f038c0882cf6970cef03fb6d32e298e6b6?s=96&d=identicon&r=g\",\"width\":96,\"height\":96,\"caption\":\"philahistory\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#webpage\",\"url\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/\",\"name\":\"Hollywood en huelga - Workers' Voice\\\/La Voz\",\"description\":\"(Tambi\\u00e9n en espa\\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/author\\\/philahistory\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/author\\\/philahistory\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/workersvoiceus.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Writers-Robert-Hanashiro-USA-Today.webp?fit=660%2C415&ssl=1\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#mainImage\",\"width\":660,\"height\":415},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/2023\\\/07\\\/22\\\/hollywood-on-strike\\\/#mainImage\"},\"datePublished\":\"2023-07-22T20:54:01-04:00\",\"dateModified\":\"2023-07-22T23:36:03-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/\",\"name\":\"{:en}Workers' Voice\\\/La Voz de los Trabajadores{:}{:es}La Voz de los Trabajadores{:}\",\"description\":\"Una fusion de Socialist Resurgence y La Voz de los Trabajadores\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/workersvoiceus.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Hollywood en huelga - Workers' Voice\/La Voz","description":"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...","canonical_url":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#blogposting","name":"Hollywood en huelga - Workers' Voice\/La Voz","headline":"Hollywood en huelga","author":{"@id":"https:\/\/workersvoiceus.org\/es\/author\/philahistory\/#author"},"publisher":{"@id":"https:\/\/workersvoiceus.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?fit=660%2C415&ssl=1","width":660,"height":415},"datePublished":"2023-07-22T20:54:01-04:00","dateModified":"2023-07-22T23:36:03-04:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#webpage"},"isPartOf":{"@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#webpage"},"articleSection":"Books, films, arts | Libros, peliculas, arte, Labor | Lucha obrera"},{"@type":"BreadcrumbList","@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/workersvoiceus.org\/es#listItem","position":1,"name":"Home","item":"https:\/\/workersvoiceus.org\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/workersvoiceus.org\/es\/category\/the-arts\/#listItem","name":"Books, films, arts | Libros, peliculas, arte"}},{"@type":"ListItem","@id":"https:\/\/workersvoiceus.org\/es\/category\/the-arts\/#listItem","position":2,"name":"Books, films, arts | Libros, peliculas, arte","item":"https:\/\/workersvoiceus.org\/es\/category\/the-arts\/","nextItem":{"@type":"ListItem","@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#listItem","name":"Hollywood en huelga"},"previousItem":{"@type":"ListItem","@id":"https:\/\/workersvoiceus.org\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#listItem","position":3,"name":"Hollywood en huelga","previousItem":{"@type":"ListItem","@id":"https:\/\/workersvoiceus.org\/es\/category\/the-arts\/#listItem","name":"Books, films, arts | Libros, peliculas, arte"}}]},{"@type":"Organization","@id":"https:\/\/workersvoiceus.org\/es\/#organization","name":"Workers' Voice\/La Voz de los Trabajadores","description":"Una fusion de Socialist Resurgence y La Voz de los Trabajadores","url":"https:\/\/workersvoiceus.org\/es\/","sameAs":["https:\/\/www.facebook.com\/workersvoiceus","https:\/\/twitter.com\/WorkersVoice_US","https:\/\/www.instagram.com\/workersvoiceus\/"]},{"@type":"Person","@id":"https:\/\/workersvoiceus.org\/es\/author\/philahistory\/#author","url":"https:\/\/workersvoiceus.org\/es\/author\/philahistory\/","name":"philahistory","image":{"@type":"ImageObject","@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4060a01da4b5637608d72866d0d000f038c0882cf6970cef03fb6d32e298e6b6?s=96&d=identicon&r=g","width":96,"height":96,"caption":"philahistory"}},{"@type":"WebPage","@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#webpage","url":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/","name":"Hollywood en huelga - Workers' Voice\/La Voz","description":"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/workersvoiceus.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#breadcrumblist"},"author":{"@id":"https:\/\/workersvoiceus.org\/es\/author\/philahistory\/#author"},"creator":{"@id":"https:\/\/workersvoiceus.org\/es\/author\/philahistory\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?fit=660%2C415&ssl=1","@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#mainImage","width":660,"height":415},"primaryImageOfPage":{"@id":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/#mainImage"},"datePublished":"2023-07-22T20:54:01-04:00","dateModified":"2023-07-22T23:36:03-04:00"},{"@type":"WebSite","@id":"https:\/\/workersvoiceus.org\/es\/#website","url":"https:\/\/workersvoiceus.org\/es\/","name":"{:en}Workers' Voice\/La Voz de los Trabajadores{:}{:es}La Voz de los Trabajadores{:}","description":"Una fusion de Socialist Resurgence y La Voz de los Trabajadores","inLanguage":"es-ES","publisher":{"@id":"https:\/\/workersvoiceus.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"La Voz de los Trabajadores - Una fusion de Socialist Resurgence y La Voz de los Trabajadores","og:type":"article","og:title":"Hollywood en huelga - Workers' Voice\/La Voz","og:description":"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...","og:url":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/","og:image":"https:\/\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp","og:image:secure_url":"https:\/\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp","og:image:width":660,"og:image:height":415,"article:published_time":"2023-07-23T00:54:01+00:00","article:modified_time":"2023-07-23T03:36:03+00:00","article:publisher":"https:\/\/www.facebook.com\/workersvoiceus","twitter:card":"summary","twitter:site":"@WorkersVoice_US","twitter:title":"Hollywood en huelga - Workers' Voice\/La Voz","twitter:description":"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...","twitter:creator":"@WorkersVoice_US","twitter:image":"https:\/\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp"},"aioseo_meta_data":{"post_id":"17817","title":"#post_title #separator_sa Workers' Voice\/La Voz","description":"(Tambi\u00e9n en espa\u00f1ol) On May 2, over 11,000 workers from the Writers Guild of America (WGA) walked off the job and initiated their second strike of the 21st century. At stake for workers in the industry are...","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-07-23 00:54:01","updated":"2025-06-04 10:22:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/workersvoiceus.org\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/workersvoiceus.org\/es\/category\/the-arts\/\" title=\"Books, films, arts | Libros, peliculas, arte\">Books, films, arts | Libros, peliculas, arte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHollywood en huelga\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/workersvoiceus.org\/es"},{"label":"Books, films, arts | Libros, peliculas, arte","link":"https:\/\/workersvoiceus.org\/es\/category\/the-arts\/"},{"label":"Hollywood en huelga","link":"https:\/\/workersvoiceus.org\/es\/2023\/07\/22\/hollywood-on-strike\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/workersvoiceus.org\/wp-content\/uploads\/2023\/07\/Writers-Robert-Hanashiro-USA-Today.webp?fit=660%2C415&ssl=1","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdQxqk-4Dn","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts\/17817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/users\/13882115"}],"replies":[{"embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/comments?post=17817"}],"version-history":[{"count":4,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts\/17817\/revisions"}],"predecessor-version":[{"id":17830,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/posts\/17817\/revisions\/17830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/media\/17819"}],"wp:attachment":[{"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/media?parent=17817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/categories?post=17817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/workersvoiceus.org\/es\/wp-json\/wp\/v2\/tags?post=17817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}